{"id":3959,"date":"2019-07-22T13:18:19","date_gmt":"2019-07-22T13:18:19","guid":{"rendered":"http:\/\/ogrzewania.net.pl\/?post_type=product&#038;p=3959"},"modified":"2024-04-12T18:49:03","modified_gmt":"2024-04-12T18:49:03","slug":"wiazka-adapter-iso-czujnika-cisnienia-powietrza-eberspaecher-221000333100","status":"publish","type":"product","link":"http:\/\/ogrzewania.net.pl\/en\/shop\/product\/wiazka-adapter-iso-czujnika-cisnienia-powietrza-eberspaecher-221000333100","title":{"rendered":"Eberspaecher ISO cable adapter air pressure sensor | 221000333100"},"content":{"rendered":"<strong>Photos overview:<\/strong><\/p>\n<div class=\"su-custom-gallery su-custom-gallery-align-left su-custom-gallery-title-never su-lightbox-gallery\"><div class=\"su-custom-gallery-slide\" style=\"width:140px;height:90px\"><a href=\"http:\/\/ogrzewania.net.pl\/wp-content\/uploads\/2019\/07\/221000333100.png\" title=\"221000333100\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/ogrzewania.net.pl\/wp-content\/uploads\/2019\/07\/221000333100-140x90.png\" alt=\"221000333100\" width=\"140\" height=\"90\" \/><span class=\"su-custom-gallery-title\">221000333100<\/span><\/a><\/div><div class=\"su-clear\"><\/div><\/div>\n<p>Eberspaecher ISO cable adapter air pressure sensor 221000333100<\/p>\n<p><strong>Details:<\/strong><\/p>\n<ul>\n<li>Original Eberspaecher product<\/li>\n<li>Catalogue number&nbsp;221000333100<\/li>\n<li>Dedictated to control devices<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13\" src=\"http:\/\/ogrzewania.net.pl\/wp-content\/uploads\/2016\/10\/eberspracher-400x123.png\" alt=\"eberspracher\" width=\"182\" height=\"56\" srcset=\"http:\/\/ogrzewania.net.pl\/wp-content\/uploads\/2016\/10\/eberspracher-400x123.png 400w, http:\/\/ogrzewania.net.pl\/wp-content\/uploads\/2016\/10\/eberspracher-140x43.png 140w, http:\/\/ogrzewania.net.pl\/wp-content\/uploads\/2016\/10\/eberspracher.png 460w\" sizes=\"(max-width: 182px) 100vw, 182px\" \/><\/p>\n<ul>\n<li>DHL delivery<\/li>\n<li>producer warranty<\/li>\n<li>available in our traditional shop in Poland<\/li>\n<li>we do offer installation service<\/li>\n<\/ul>\n","protected":false},"featured_media":3960,"template":"","meta":[],"pwb-brand":[462],"product_cat":[347,42,91,95],"product_tag":[],"brands":[{"id":462,"name":"Eberspacher","slug":"eberspacher"}],"_links":{"self":[{"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/product\/3959"}],"collection":[{"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/media\/3960"}],"wp:attachment":[{"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/media?parent=3959"}],"wp:term":[{"taxonomy":"pwb-brand","embeddable":true,"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/pwb-brand?post=3959"},{"taxonomy":"product_cat","embeddable":true,"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/product_cat?post=3959"},{"taxonomy":"product_tag","embeddable":true,"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/product_tag?post=3959"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}