{"id":4518,"date":"2019-08-08T14:52:31","date_gmt":"2019-08-08T14:52:31","guid":{"rendered":"http:\/\/ogrzewania.net.pl\/?post_type=product&#038;p=4518"},"modified":"2024-04-12T18:51:16","modified_gmt":"2024-04-12T18:51:16","slug":"obejma-d-29-15-webasto-1320235a","status":"publish","type":"product","link":"http:\/\/ogrzewania.net.pl\/en\/shop\/product\/obejma-d-29-15-webasto-1320235a","title":{"rendered":"Webasto d-29-15 pipe clip | 1320235A"},"content":{"rendered":"<strong>Photos overview:<\/strong><\/p>\n<div class=\"su-custom-gallery su-custom-gallery-align-left su-custom-gallery-title-never su-lightbox-gallery\"><div class=\"su-custom-gallery-slide\" style=\"width:140px;height:90px\"><a href=\"http:\/\/ogrzewania.net.pl\/wp-content\/uploads\/2019\/08\/1320235A.png\" title=\"1320235A\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/ogrzewania.net.pl\/wp-content\/uploads\/2019\/08\/1320235A-140x90.png\" alt=\"1320235A\" width=\"140\" height=\"90\" \/><span class=\"su-custom-gallery-title\">1320235A<\/span><\/a><\/div><div class=\"su-clear\"><\/div><\/div>\n<p>Webasto d-29-15 pipe clip 1320235A<\/p>\n<p><strong>Details:<\/strong><\/p>\n<ul>\n<li>Original Webasto product<\/li>\n<li>Catalogue number&nbsp;1320235A<\/li>\n<li>Diameter 29 mm<\/li>\n<li>Suitable for&nbsp;Air Top 2000 STC, Air Top Evo 40\/55, Thermo Top Evo, Thermo Pro 50 Eco, Thermo Top C\/E, Thermo Pro 90, DBW 2010\/2016 heaters<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-863\" src=\"http:\/\/ogrzewania.net.pl\/wp-content\/uploads\/2017\/01\/webastologo.jpg\" alt=\"webastologo\" width=\"192\" height=\"42\" srcset=\"http:\/\/ogrzewania.net.pl\/wp-content\/uploads\/2017\/01\/webastologo.jpg 360w, http:\/\/ogrzewania.net.pl\/wp-content\/uploads\/2017\/01\/webastologo-140x31.jpg 140w\" sizes=\"(max-width: 192px) 100vw, 192px\" \/><\/p>\n<ul>\n<li>DHL delivery<\/li>\n<li>producer warranty<\/li>\n<li>available in our traditional shop in Poland<\/li>\n<li>we do offer installation service<\/li>\n<\/ul>\n","protected":false},"featured_media":4519,"template":"","meta":[],"pwb-brand":[475],"product_cat":[347,42,89],"product_tag":[],"brands":[{"id":475,"name":"Webasto","slug":"webasto"}],"_links":{"self":[{"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/product\/4518"}],"collection":[{"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/media\/4519"}],"wp:attachment":[{"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/media?parent=4518"}],"wp:term":[{"taxonomy":"pwb-brand","embeddable":true,"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/pwb-brand?post=4518"},{"taxonomy":"product_cat","embeddable":true,"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/product_cat?post=4518"},{"taxonomy":"product_tag","embeddable":true,"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/product_tag?post=4518"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}