{"id":4754,"date":"2019-08-22T12:14:58","date_gmt":"2019-08-22T12:14:58","guid":{"rendered":"http:\/\/ogrzewania.net.pl\/?post_type=product&#038;p=4754"},"modified":"2024-04-12T18:51:11","modified_gmt":"2024-04-12T18:51:11","slug":"obudowa-wylotu-air-top-35005000-webasto-98651b","status":"publish","type":"product","link":"http:\/\/ogrzewania.net.pl\/en\/shop\/product\/obudowa-wylotu-air-top-35005000-webasto-98651b","title":{"rendered":"Webasto Air Top 3500\/5000 air outlet hood | 98651B"},"content":{"rendered":"<strong>Photos overview:<\/strong><\/p>\n<div class=\"su-custom-gallery su-custom-gallery-align-left su-custom-gallery-title-never su-lightbox-gallery\"><div class=\"su-custom-gallery-slide\" style=\"width:140px;height:90px\"><a href=\"http:\/\/ogrzewania.net.pl\/wp-content\/uploads\/2019\/08\/98651B-1.png\" title=\"98651B\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/ogrzewania.net.pl\/wp-content\/uploads\/2019\/08\/98651B-1-140x90.png\" alt=\"98651B\" width=\"140\" height=\"90\" \/><span class=\"su-custom-gallery-title\">98651B<\/span><\/a><\/div><div class=\"su-clear\"><\/div><\/div>\n<p>Webasto Air Top 3500\/5000 air outlet hood 98651B<\/p>\n<p><strong>Details:<\/strong><\/p>\n<ul>\n<li>Original Webasto product<\/li>\n<li>Catalogue number&nbsp;98651B<\/li>\n<li>Diameter&nbsp;\u00d8 90 mm<\/li>\n<li>Suitable for&nbsp;Air Top 3500\/5000 heater<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-863\" src=\"http:\/\/ogrzewania.net.pl\/wp-content\/uploads\/2017\/01\/webastologo.jpg\" alt=\"webastologo\" width=\"192\" height=\"42\" srcset=\"http:\/\/ogrzewania.net.pl\/wp-content\/uploads\/2017\/01\/webastologo.jpg 360w, http:\/\/ogrzewania.net.pl\/wp-content\/uploads\/2017\/01\/webastologo-140x31.jpg 140w\" sizes=\"(max-width: 192px) 100vw, 192px\" \/><\/p>\n<ul>\n<li>DHL delivery<\/li>\n<li>producer warranty<\/li>\n<li>available in our traditional shop in Poland<\/li>\n<li>we do offer installation service<\/li>\n<\/ul>\n","protected":false},"featured_media":4772,"template":"","meta":[],"pwb-brand":[475],"product_cat":[347,42,89],"product_tag":[],"brands":[{"id":475,"name":"Webasto","slug":"webasto"}],"_links":{"self":[{"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/product\/4754"}],"collection":[{"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/media\/4772"}],"wp:attachment":[{"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/media?parent=4754"}],"wp:term":[{"taxonomy":"pwb-brand","embeddable":true,"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/pwb-brand?post=4754"},{"taxonomy":"product_cat","embeddable":true,"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/product_cat?post=4754"},{"taxonomy":"product_tag","embeddable":true,"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/product_tag?post=4754"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}