{"id":4801,"date":"2019-08-23T08:32:34","date_gmt":"2019-08-23T08:32:34","guid":{"rendered":"http:\/\/ogrzewania.net.pl\/?post_type=product&#038;p=4801"},"modified":"2024-04-12T18:44:32","modified_gmt":"2024-04-12T18:44:32","slug":"zlaczka-paliwowa-4-5x10-5-20szt-webasto-9023143a","status":"publish","type":"product","link":"http:\/\/ogrzewania.net.pl\/en\/shop\/product\/zlaczka-paliwowa-4-5x10-5-20szt-webasto-9023143a","title":{"rendered":"Webasto fuel hose 4.5&#215;10.5 20 pcs. | 9023143A"},"content":{"rendered":"<strong>Photos overview:<\/strong><\/p>\n<div class=\"su-custom-gallery su-custom-gallery-align-left su-custom-gallery-title-never su-lightbox-gallery\"><div class=\"su-custom-gallery-slide\" style=\"width:140px;height:90px\"><a href=\"http:\/\/ogrzewania.net.pl\/wp-content\/uploads\/2019\/08\/9023143A.png\" title=\"9023143A\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/ogrzewania.net.pl\/wp-content\/uploads\/2019\/08\/9023143A-140x90.png\" alt=\"9023143A\" width=\"140\" height=\"90\" \/><span class=\"su-custom-gallery-title\">9023143A<\/span><\/a><\/div><div class=\"su-clear\"><\/div><\/div>\n<p>Webasto fuel hose 4.5&#215;10.5 20 pcs. 9023143A<\/p>\n<p><strong>Details:<\/strong><\/p>\n<ul>\n<li>Original Webasto product<\/li>\n<li>Catalogue number&nbsp;9023143A<\/li>\n<li>Inside diameter 4.5 mm<\/li>\n<li>External diameter 10.5 mm<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-863\" src=\"http:\/\/ogrzewania.net.pl\/wp-content\/uploads\/2017\/01\/webastologo.jpg\" alt=\"webastologo\" width=\"192\" height=\"42\" srcset=\"http:\/\/ogrzewania.net.pl\/wp-content\/uploads\/2017\/01\/webastologo.jpg 360w, http:\/\/ogrzewania.net.pl\/wp-content\/uploads\/2017\/01\/webastologo-140x31.jpg 140w\" sizes=\"(max-width: 192px) 100vw, 192px\" \/><\/p>\n<ul>\n<li>DHL delivery<\/li>\n<li>producer warranty<\/li>\n<li>available in our traditional shop in Poland<\/li>\n<li>we do offer installation service<\/li>\n<\/ul>\n","protected":false},"featured_media":4802,"template":"","meta":[],"pwb-brand":[475],"product_cat":[347,42,109],"product_tag":[],"brands":[{"id":475,"name":"Webasto","slug":"webasto"}],"_links":{"self":[{"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/product\/4801"}],"collection":[{"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/media\/4802"}],"wp:attachment":[{"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/media?parent=4801"}],"wp:term":[{"taxonomy":"pwb-brand","embeddable":true,"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/pwb-brand?post=4801"},{"taxonomy":"product_cat","embeddable":true,"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/product_cat?post=4801"},{"taxonomy":"product_tag","embeddable":true,"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/product_tag?post=4801"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}