{"id":5031,"date":"2019-08-29T14:00:46","date_gmt":"2019-08-29T14:00:46","guid":{"rendered":"http:\/\/ogrzewania.net.pl\/?post_type=product&#038;p=5031"},"modified":"2024-04-12T18:51:05","modified_gmt":"2024-04-12T18:51:05","slug":"rura-wylotowa-d70-l90-webasto-1319433a","status":"publish","type":"product","link":"http:\/\/ogrzewania.net.pl\/en\/shop\/product\/rura-wylotowa-d70-l90-webasto-1319433a","title":{"rendered":"Webasto exhaust pipe extension D70 L=90 | 1319433A"},"content":{"rendered":"<strong>Photos overview:<\/strong><\/p>\n<div class=\"su-custom-gallery su-custom-gallery-align-left su-custom-gallery-title-never su-lightbox-gallery\"><div class=\"su-custom-gallery-slide\" style=\"width:140px;height:90px\"><a href=\"http:\/\/ogrzewania.net.pl\/wp-content\/uploads\/2019\/08\/1319433A.png\" title=\"1319433A\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/ogrzewania.net.pl\/wp-content\/uploads\/2019\/08\/1319433A-140x90.png\" alt=\"1319433A\" width=\"140\" height=\"90\" \/><span class=\"su-custom-gallery-title\">1319433A<\/span><\/a><\/div><div class=\"su-clear\"><\/div><\/div>\n<p>Webasto exhaust pipe extension D70 L=90 1319433A<\/p>\n<p><strong>Details:<\/strong><\/p>\n<ul>\n<li>Original Webasto product<\/li>\n<li>Catalogue number 1319433A<\/li>\n<li>Diameter 70 mm<\/li>\n<li>Length 90 mm<\/li>\n<li>Suitable for DW 230\/300\/350 heaters<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-863\" src=\"http:\/\/ogrzewania.net.pl\/wp-content\/uploads\/2017\/01\/webastologo.jpg\" alt=\"webastologo\" width=\"192\" height=\"42\" srcset=\"http:\/\/ogrzewania.net.pl\/wp-content\/uploads\/2017\/01\/webastologo.jpg 360w, http:\/\/ogrzewania.net.pl\/wp-content\/uploads\/2017\/01\/webastologo-140x31.jpg 140w\" sizes=\"(max-width: 192px) 100vw, 192px\" \/><\/p>\n<ul>\n<li>DHL delivery<\/li>\n<li>producer warranty<\/li>\n<li>available in our traditional shop in Poland<\/li>\n<li>we do offer installation service<\/li>\n<\/ul>\n","protected":false},"featured_media":5032,"template":"","meta":[],"pwb-brand":[475],"product_cat":[347,42,89],"product_tag":[],"brands":[{"id":475,"name":"Webasto","slug":"webasto"}],"_links":{"self":[{"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/product\/5031"}],"collection":[{"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/media\/5032"}],"wp:attachment":[{"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/media?parent=5031"}],"wp:term":[{"taxonomy":"pwb-brand","embeddable":true,"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/pwb-brand?post=5031"},{"taxonomy":"product_cat","embeddable":true,"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/product_cat?post=5031"},{"taxonomy":"product_tag","embeddable":true,"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/product_tag?post=5031"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}