{"id":6326,"date":"2022-08-06T07:49:27","date_gmt":"2022-08-06T07:49:27","guid":{"rendered":"http:\/\/ogrzewania.net.pl\/?post_type=product&#038;p=6326"},"modified":"2024-04-23T12:46:18","modified_gmt":"2024-04-23T12:46:18","slug":"sterownik-a2-d2l-12v-eberspaecher-252721995000-2","status":"publish","type":"product","link":"http:\/\/ogrzewania.net.pl\/en\/shop\/product\/sterownik-a2-d2l-12v-eberspaecher-252721995000-2","title":{"rendered":"Controller A2 D2L 12V Eberspaecher | 252721995000"},"content":{"rendered":"<strong>Photos overview:<\/strong><\/p>\n<div class=\"su-custom-gallery su-custom-gallery-align-left su-custom-gallery-title-never su-lightbox-gallery\"><div class=\"su-custom-gallery-slide\" style=\"width:140px;height:90px\"><a href=\"http:\/\/ogrzewania.net.pl\/wp-content\/uploads\/2022\/08\/252721995000.png\" title=\"252721995000\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/ogrzewania.net.pl\/wp-content\/uploads\/2022\/08\/252721995000-140x90.png\" alt=\"252721995000\" width=\"140\" height=\"90\" \/><span class=\"su-custom-gallery-title\">252721995000<\/span><\/a><\/div><div class=\"su-clear\"><\/div><\/div>\n<p><strong>Details:<\/strong><\/p>\n<p>Original product of Eberspaecher<\/p>\n<p>Catalogue number 252721995000<\/p>\n<p>Suitable for Airtronic 2 D2L 12V,<\/p>","protected":false},"excerpt":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13\" src=\"http:\/\/ogrzewania.net.pl\/wp-content\/uploads\/2016\/10\/eberspracher-400x123.png\" alt=\"eberspracher\" width=\"182\" height=\"56\" srcset=\"http:\/\/ogrzewania.net.pl\/wp-content\/uploads\/2016\/10\/eberspracher-400x123.png 400w, http:\/\/ogrzewania.net.pl\/wp-content\/uploads\/2016\/10\/eberspracher-140x43.png 140w, http:\/\/ogrzewania.net.pl\/wp-content\/uploads\/2016\/10\/eberspracher.png 460w\" sizes=\"(max-width: 182px) 100vw, 182px\" \/><\/p>\n<ul>\n<li>DHL delivery<\/li>\n<li>producer warranty<\/li>\n<li>available in our traditional shop in Poland<\/li>\n<li>we do offer installation service<\/li>\n<\/ul>\n","protected":false},"featured_media":6327,"template":"","meta":[],"pwb-brand":[462],"product_cat":[347,42,91],"product_tag":[],"brands":[{"id":462,"name":"Eberspacher","slug":"eberspacher"}],"_links":{"self":[{"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/product\/6326"}],"collection":[{"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/media\/6327"}],"wp:attachment":[{"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/media?parent=6326"}],"wp:term":[{"taxonomy":"pwb-brand","embeddable":true,"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/pwb-brand?post=6326"},{"taxonomy":"product_cat","embeddable":true,"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/product_cat?post=6326"},{"taxonomy":"product_tag","embeddable":true,"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/product_tag?post=6326"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}