{"id":6638,"date":"2022-08-11T13:36:24","date_gmt":"2022-08-11T13:36:24","guid":{"rendered":"http:\/\/ogrzewania.net.pl\/?post_type=product&#038;p=6638"},"modified":"2024-04-12T18:21:51","modified_gmt":"2024-04-12T18:21:51","slug":"parownica-nagrzewnica-falkon-plus-kombi-kalori-ed6-o-55-mm-24v-eberspaecher-830012219133","status":"publish","type":"product","link":"http:\/\/ogrzewania.net.pl\/en\/shop\/product\/parownica-nagrzewnica-falkon-plus-kombi-kalori-ed6-o-55-mm-24v-eberspaecher-830012219133","title":{"rendered":"Evaporator-Heater  Falkon Plus Kombi Kalori ED6 (\u00d8 55 mm) 24V Eberspaecher | 830012219133"},"content":{"rendered":"<strong>Photos overview:<\/strong><\/p>\n<div class=\"su-custom-gallery su-custom-gallery-align-left su-custom-gallery-title-hover su-lightbox-gallery\"><div class=\"su-custom-gallery-slide\" style=\"width:90px;height:90px\"><a href=\"http:\/\/ogrzewania.net.pl\/wp-content\/uploads\/2022\/08\/830012219032-56.png\" target=\"_blank\" title=\"830012219032-56\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/ogrzewania.net.pl\/wp-content\/uploads\/2022\/08\/830012219032-56-90x90.png\" alt=\"830012219032-56\" width=\"90\" height=\"90\" \/><span class=\"su-custom-gallery-title\">830012219032-56<\/span><\/a><\/div><div class=\"su-custom-gallery-slide\" style=\"width:90px;height:90px\"><a href=\"http:\/\/ogrzewania.net.pl\/wp-content\/uploads\/2022\/08\/830012219032.png\" target=\"_blank\" title=\"830012219032\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/ogrzewania.net.pl\/wp-content\/uploads\/2022\/08\/830012219032-90x90.png\" alt=\"830012219032\" width=\"90\" height=\"90\" \/><span class=\"su-custom-gallery-title\">830012219032<\/span><\/a><\/div><div class=\"su-custom-gallery-slide\" style=\"width:90px;height:90px\"><a href=\"http:\/\/ogrzewania.net.pl\/wp-content\/uploads\/2022\/08\/830012219032-55.png\" target=\"_blank\" title=\"830012219032-55\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/ogrzewania.net.pl\/wp-content\/uploads\/2022\/08\/830012219032-55-90x90.png\" alt=\"830012219032-55\" width=\"90\" height=\"90\" \/><span class=\"su-custom-gallery-title\">830012219032-55<\/span><\/a><\/div><div class=\"su-clear\"><\/div><\/div>\n<p><strong>Details:<\/strong><\/p>\n<ul>\n<li>Heating power 10 kW<\/li>\n<li>Cooling output 9 kW<\/li>\n<li>Airflow 870 m\u00b3\/h<\/li>\n<li>Electricity consumption 430 W<\/li>\n<li>Water connection \u00d8 16 mm<\/li>\n<li>Ventilation speed 3<\/li>\n<\/ul>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13\" src=\"http:\/\/ogrzewania.net.pl\/wp-content\/uploads\/2016\/10\/eberspracher-400x123.png\" alt=\"eberspracher\" width=\"182\" height=\"56\" srcset=\"http:\/\/ogrzewania.net.pl\/wp-content\/uploads\/2016\/10\/eberspracher-400x123.png 400w, http:\/\/ogrzewania.net.pl\/wp-content\/uploads\/2016\/10\/eberspracher-140x43.png 140w, http:\/\/ogrzewania.net.pl\/wp-content\/uploads\/2016\/10\/eberspracher.png 460w\" sizes=\"(max-width: 182px) 100vw, 182px\" \/><\/p>\n<ul>\n<li>DHL delivery<\/li>\n<li>producer warranty<\/li>\n<li>available in our traditional shop in Poland<\/li>\n<li>we do offer installation service<\/li>\n<\/ul>\n","protected":false},"featured_media":6635,"template":"","meta":[],"pwb-brand":[462],"product_cat":[347,354,366],"product_tag":[],"brands":[{"id":462,"name":"Eberspacher","slug":"eberspacher"}],"_links":{"self":[{"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/product\/6638"}],"collection":[{"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/media\/6635"}],"wp:attachment":[{"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/media?parent=6638"}],"wp:term":[{"taxonomy":"pwb-brand","embeddable":true,"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/pwb-brand?post=6638"},{"taxonomy":"product_cat","embeddable":true,"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/product_cat?post=6638"},{"taxonomy":"product_tag","embeddable":true,"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/product_tag?post=6638"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}