{"id":6904,"date":"2022-08-25T09:17:01","date_gmt":"2022-08-25T09:17:01","guid":{"rendered":"http:\/\/ogrzewania.net.pl\/?post_type=product&#038;p=6904"},"modified":"2026-02-25T14:14:21","modified_gmt":"2026-02-25T14:14:21","slug":"palnik-zestaw-kompletny-air-top-evo-2000-renault-webasto-7482382342","status":"publish","type":"product","link":"http:\/\/ogrzewania.net.pl\/en\/shop\/product\/palnik-zestaw-kompletny-air-top-evo-2000-renault-webasto-7482382342","title":{"rendered":"Burner Kit Air Top EVO 2000 Renault Webasto | 7482382342"},"content":{"rendered":"<strong>Photos overview:<\/strong><\/p>\n<div class=\"su-custom-gallery su-custom-gallery-align-left su-custom-gallery-title-always su-lightbox-gallery\"><div class=\"su-custom-gallery-slide\" style=\"width:120px;height:90px\"><a href=\"http:\/\/ogrzewania.net.pl\/wp-content\/uploads\/2022\/08\/82382342-2.png\" target=\"_blank\" title=\"82382342-2\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/ogrzewania.net.pl\/wp-content\/uploads\/2022\/08\/82382342-2-120x90.png\" alt=\"82382342-2\" width=\"120\" height=\"90\" \/><span class=\"su-custom-gallery-title\">82382342-2<\/span><\/a><\/div><div class=\"su-clear\"><\/div><\/div>\n<p><strong>Details:<\/strong><\/p>\n<ul>\n<li>kit contains:&nbsp;burner, flames temperature sensor and glow pin<\/li>\n<li>dedicated for: Air Top EVO 2000<\/li>\n<li>used in: Renault<\/li>\n<li>catalogue number: 9034036B 9034036A<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-863\" src=\"http:\/\/ogrzewania.net.pl\/wp-content\/uploads\/2017\/01\/webastologo.jpg\" alt=\"webastologo\" width=\"192\" height=\"42\" srcset=\"http:\/\/ogrzewania.net.pl\/wp-content\/uploads\/2017\/01\/webastologo.jpg 360w, http:\/\/ogrzewania.net.pl\/wp-content\/uploads\/2017\/01\/webastologo-140x31.jpg 140w\" sizes=\"(max-width: 192px) 100vw, 192px\" \/><\/p>\n<ul>\n<li>DHL delivery<\/li>\n<li>producer warranty<\/li>\n<li>available in our traditional shop in Poland<\/li>\n<li>we do offer installation service<\/li>\n<\/ul>\n","protected":false},"featured_media":6901,"template":"","meta":[],"pwb-brand":[475],"product_cat":[347,42,109],"product_tag":[],"brands":[{"id":475,"name":"Webasto","slug":"webasto"}],"_links":{"self":[{"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/product\/6904"}],"collection":[{"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/media\/6901"}],"wp:attachment":[{"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/media?parent=6904"}],"wp:term":[{"taxonomy":"pwb-brand","embeddable":true,"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/pwb-brand?post=6904"},{"taxonomy":"product_cat","embeddable":true,"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/product_cat?post=6904"},{"taxonomy":"product_tag","embeddable":true,"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/product_tag?post=6904"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}