{"id":7116,"date":"2022-08-31T13:47:06","date_gmt":"2022-08-31T13:47:06","guid":{"rendered":"http:\/\/ogrzewania.net.pl\/?post_type=product&#038;p=7116"},"modified":"2024-04-12T18:43:49","modified_gmt":"2024-04-12T18:43:49","slug":"kabel-diagnostyczny-multicontrol-webasto-9029674b","status":"publish","type":"product","link":"http:\/\/ogrzewania.net.pl\/en\/shop\/product\/kabel-diagnostyczny-multicontrol-webasto-9029674b","title":{"rendered":"Diagnosis cable MultiControl Webasto | 9029674B"},"content":{"rendered":"<strong>Photos overview:<\/strong><\/p>\n<div class=\"su-custom-gallery su-custom-gallery-align-left su-custom-gallery-title-always su-lightbox-gallery\"><div class=\"su-custom-gallery-slide\" style=\"width:120px;height:90px\"><a href=\"http:\/\/ogrzewania.net.pl\/wp-content\/uploads\/2022\/08\/9029674B.png\" target=\"_blank\" title=\"9029674B\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/ogrzewania.net.pl\/wp-content\/uploads\/2022\/08\/9029674B-120x90.png\" alt=\"9029674B\" width=\"120\" height=\"90\" \/><span class=\"su-custom-gallery-title\">9029674B<\/span><\/a><\/div><div class=\"su-clear\"><\/div><\/div>\n<p><strong>Details:<\/strong><\/p>\n<ul>\n<li>\n<div class=\"col-12 product-information\">\n<div class=\"row\">\n<div class=\"col-12 detail-container\">\n<div class=\"row\">\n<div class=\"col-12 col-lg-5 title\">Further Technical Property for digital timer MultiControl and SmartControl<\/div>\n<\/div>\n<div class=\"row\">\n<div class=\"col-12 col-lg-5 title\">Packaging dimension (L x W x H) 100 \/ 70 \/ 20 mm<\/div>\n<\/div>\n<div class=\"row\">\n<div class=\"col-12 col-lg-5 title\">Weight (kg) 21 g<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-863\" src=\"http:\/\/ogrzewania.net.pl\/wp-content\/uploads\/2017\/01\/webastologo.jpg\" alt=\"webastologo\" width=\"192\" height=\"42\" srcset=\"http:\/\/ogrzewania.net.pl\/wp-content\/uploads\/2017\/01\/webastologo.jpg 360w, http:\/\/ogrzewania.net.pl\/wp-content\/uploads\/2017\/01\/webastologo-140x31.jpg 140w\" sizes=\"(max-width: 192px) 100vw, 192px\" \/><\/p>\n<ul>\n<li>DHL delivery<\/li>\n<li>producer warranty<\/li>\n<li>available in our traditional shop in Poland<\/li>\n<li>we do offer installation service<\/li>\n<\/ul>\n","protected":false},"featured_media":7117,"template":"","meta":[],"pwb-brand":[475],"product_cat":[347,42,109,94],"product_tag":[],"brands":[{"id":475,"name":"Webasto","slug":"webasto"}],"_links":{"self":[{"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/product\/7116"}],"collection":[{"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/media\/7117"}],"wp:attachment":[{"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/media?parent=7116"}],"wp:term":[{"taxonomy":"pwb-brand","embeddable":true,"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/pwb-brand?post=7116"},{"taxonomy":"product_cat","embeddable":true,"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/product_cat?post=7116"},{"taxonomy":"product_tag","embeddable":true,"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/product_tag?post=7116"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}