{"id":7485,"date":"2023-02-15T10:32:23","date_gmt":"2023-02-15T10:32:23","guid":{"rendered":"http:\/\/ogrzewania.net.pl\/?post_type=product&#038;p=7485"},"modified":"2024-04-12T18:34:51","modified_gmt":"2024-04-12T18:34:51","slug":"czujnik-temperatury-spalin-ttp120-150-zawiera-czesci-montazowe-webasto-9036851a","status":"publish","type":"product","link":"http:\/\/ogrzewania.net.pl\/en\/shop\/product\/czujnik-temperatury-spalin-ttp120-150-zawiera-czesci-montazowe-webasto-9036851a","title":{"rendered":"Exhaust temperature sensor TTP120\/150 (Includes mounting parts) Webasto | 9036851A"},"content":{"rendered":"<strong>Photos overview:<\/strong><\/p>\n<div class=\"su-custom-gallery su-custom-gallery-align-left su-custom-gallery-title-always su-lightbox-gallery\"><div class=\"su-custom-gallery-slide\" style=\"width:120px;height:90px\"><a href=\"http:\/\/ogrzewania.net.pl\/wp-content\/uploads\/2023\/02\/Bez-nazwy5.png\" target=\"_blank\" title=\"Bez nazwy5\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/ogrzewania.net.pl\/wp-content\/uploads\/2023\/02\/Bez-nazwy5-120x90.png\" alt=\"Bez nazwy5\" width=\"120\" height=\"90\" \/><span class=\"su-custom-gallery-title\">Bez nazwy5<\/span><\/a><\/div><div class=\"su-clear\"><\/div><\/div>\n<p>(5)<\/p>\n<p><strong>Details:<\/strong><\/p>\n<ul>\n<li>Original product of Webasto<\/li>\n<li>Catalogue number 9036851A<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-863\" src=\"http:\/\/ogrzewania.net.pl\/wp-content\/uploads\/2017\/01\/webastologo.jpg\" alt=\"webastologo\" width=\"192\" height=\"42\" srcset=\"http:\/\/ogrzewania.net.pl\/wp-content\/uploads\/2017\/01\/webastologo.jpg 360w, http:\/\/ogrzewania.net.pl\/wp-content\/uploads\/2017\/01\/webastologo-140x31.jpg 140w\" sizes=\"(max-width: 192px) 100vw, 192px\" \/><\/p>\n<ul>\n<li>DHL delivery<\/li>\n<li>producer warranty<\/li>\n<li>available in our traditional shop in Poland<\/li>\n<li>we do offer installation service<\/li>\n<\/ul>\n","protected":false},"featured_media":7483,"template":"","meta":[],"pwb-brand":[475],"product_cat":[347,42,109,94],"product_tag":[],"brands":[{"id":475,"name":"Webasto","slug":"webasto"}],"_links":{"self":[{"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/product\/7485"}],"collection":[{"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/media\/7483"}],"wp:attachment":[{"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/media?parent=7485"}],"wp:term":[{"taxonomy":"pwb-brand","embeddable":true,"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/pwb-brand?post=7485"},{"taxonomy":"product_cat","embeddable":true,"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/product_cat?post=7485"},{"taxonomy":"product_tag","embeddable":true,"href":"http:\/\/ogrzewania.net.pl\/en\/wp-json\/wp\/v2\/product_tag?post=7485"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}